{"id":13047,"date":"2025-03-20T16:21:18","date_gmt":"2025-03-20T15:21:18","guid":{"rendered":"https:\/\/mitur.gob.sv\/utravel\/sin-categoria\/restaurante-cucoliche\/"},"modified":"2025-03-20T16:21:18","modified_gmt":"2025-03-20T15:21:18","slug":"restaurante-cucoliche","status":"publish","type":"post","link":"https:\/\/elsalvador.travel\/esp\/restaurante-cucoliche\/","title":{"rendered":"Restaurante Cucoliche"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[224,223],"tags":[189,27],"class_list":["post-13047","post","type-post","status-publish","format-standard","hentry","category-alimentacion-2","category-servicio","tag-alimentacionsan-miguel","tag-san-miguel"],"acf":{"photo_gallery":{"galeria_de_imagenes":[[]]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:42:26","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/elsalvador.travel\/esp\/wp-json\/wp\/v2\/posts\/13047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elsalvador.travel\/esp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elsalvador.travel\/esp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elsalvador.travel\/esp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elsalvador.travel\/esp\/wp-json\/wp\/v2\/comments?post=13047"}],"version-history":[{"count":0,"href":"https:\/\/elsalvador.travel\/esp\/wp-json\/wp\/v2\/posts\/13047\/revisions"}],"wp:attachment":[{"href":"https:\/\/elsalvador.travel\/esp\/wp-json\/wp\/v2\/media?parent=13047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elsalvador.travel\/esp\/wp-json\/wp\/v2\/categories?post=13047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elsalvador.travel\/esp\/wp-json\/wp\/v2\/tags?post=13047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}