{"id":3159,"date":"2025-03-08T21:24:48","date_gmt":"2025-03-08T20:24:48","guid":{"rendered":"https:\/\/mitur.gob.sv\/travelsite\/?p=3159"},"modified":"2025-03-08T21:24:48","modified_gmt":"2025-03-08T20:24:48","slug":"ilobasco-el-corazon-artesanal-de-el-salvador","status":"publish","type":"post","link":"https:\/\/elsalvador.travel\/esp\/en\/ilobasco-el-corazon-artesanal-de-el-salvador\/","title":{"rendered":"Ilobasco, el coraz\u00f3n artesanal de El Salvador"},"content":{"rendered":"<p>Esta pintoresca ciudad, ubicada en la regi\u00f3n central, a 60 kil\u00f3metros de San Salvador, es un tesoro que resguarda la tradici\u00f3n artesanal y la calidez de su gente, y ofrece una experiencia \u00fanica a los visitantes.<\/p>\n<p>Conocida principalmente por su destacada producci\u00f3n de cer\u00e1mica, Ilobasco es un destino ideal para quienes desean conocer sobre la cultura y las artesan\u00edas salvadore\u00f1as.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-3160\" src=\"https:\/\/mitur.gob.sv\/travelsite\/wp-content\/uploads\/2025\/03\/ilobasco-02.jpg\" alt=\"\" width=\"1920\" height=\"1280\" srcset=\"https:\/\/elsalvador.travel\/esp\/wp-content\/uploads\/2025\/03\/ilobasco-02.jpg 1920w, https:\/\/elsalvador.travel\/esp\/wp-content\/uploads\/2025\/03\/ilobasco-02-300x200.jpg 300w, https:\/\/elsalvador.travel\/esp\/wp-content\/uploads\/2025\/03\/ilobasco-02-1024x683.jpg 1024w, https:\/\/elsalvador.travel\/esp\/wp-content\/uploads\/2025\/03\/ilobasco-02-768x512.jpg 768w, https:\/\/elsalvador.travel\/esp\/wp-content\/uploads\/2025\/03\/ilobasco-02-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<p>Es famoso por su cer\u00e1mica, especialmente las miniaturas y las figuras tradicionales. Las visitas a las tiendas y a los talleres son una parada obligatoria. Aqu\u00ed, puedes observar el proceso de creaci\u00f3n de piezas \u00fanicas, desde el modelado del barro hasta el pintado final.<\/p>\n<p>Estas son algunas opciones donde puedes vivir la experiencia:<\/p>\n<p>El Centro de Desarrollo Artesanal (CEDART).<br \/>\nLa Asociaci\u00f3n Movimiento de J\u00f3venes Encuentristas (MOJE).<\/p>\n<p>Si lo que buscas es conocer sobre la cultura y el fervor religioso del lugar, puedes recorrer los diferentes templos.<\/p>\n<p>La iglesia principal de Ilobasco, San Miguel Arc\u00e1ngel, que data de 1880. Se encuentra ubicada frente al Parque Central Enrique Hoyos, en el centro de la ciudad, ofreciendo a los visitantes una visi\u00f3n de la historia y la fe de la comunidad local.<\/p>\n<p>Tambi\u00e9n puedes visitar las iglesias El Calvario y Nuestra Se\u00f1ora de Los Desamparados.<\/p>\n<p>Las fiestas patronales son uno de los momentos m\u00e1s destacados, celebradas en honor a San Miguel Arc\u00e1ngel, del 20 al 29 de septiembre.<\/p>\n<p>Durante esta festividad, la ciudad se llena de color y alegr\u00eda, con desfiles, m\u00fasica en vivo, danzas tradicionales y, por supuesto, muchas oportunidades para comprar artesan\u00edas y degustar la comida local.<\/p>\n<p>Otra actividad de la que puedes disfrutar es del Festival del Barro, que en 2024 se realiza del 27 y 28 de julio, donde habr\u00e1 presentaciones art\u00edsticas, competencias de alfareros, tours y gastronom\u00eda.<\/p>\n<p>Si te encuentras por la zona tambi\u00e9n puedes hacer una visita por la Casa Hacienda y las Heliconas de Asturias.<\/p>\n<p>Ilobasco es un destino que combina tradici\u00f3n, cultura y naturaleza, ofreciendo una experiencia enriquecedora para todos sus visitantes.<\/p>","protected":false},"excerpt":{"rendered":"<p>Esta pintoresca ciudad, ubicada en la regi\u00f3n central, a 60 kil\u00f3metros de San Salvador, es un tesoro que resguarda la tradici\u00f3n artesanal y la calidez de su gente, y ofrece una experiencia \u00fanica a los visitantes. Conocida principalmente por su destacada producci\u00f3n de cer\u00e1mica, Ilobasco es un destino ideal para quienes desean conocer sobre la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3161,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[157],"tags":[],"class_list":["post-3159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article"],"acf":{"photo_gallery":{"galeria_de_imagenes":[[]]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 23:38:17","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/elsalvador.travel\/esp\/en\/wp-json\/wp\/v2\/posts\/3159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elsalvador.travel\/esp\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elsalvador.travel\/esp\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elsalvador.travel\/esp\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elsalvador.travel\/esp\/en\/wp-json\/wp\/v2\/comments?post=3159"}],"version-history":[{"count":1,"href":"https:\/\/elsalvador.travel\/esp\/en\/wp-json\/wp\/v2\/posts\/3159\/revisions"}],"predecessor-version":[{"id":3162,"href":"https:\/\/elsalvador.travel\/esp\/en\/wp-json\/wp\/v2\/posts\/3159\/revisions\/3162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elsalvador.travel\/esp\/en\/wp-json\/wp\/v2\/media\/3161"}],"wp:attachment":[{"href":"https:\/\/elsalvador.travel\/esp\/en\/wp-json\/wp\/v2\/media?parent=3159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elsalvador.travel\/esp\/en\/wp-json\/wp\/v2\/categories?post=3159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elsalvador.travel\/esp\/en\/wp-json\/wp\/v2\/tags?post=3159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}