{"id":13016,"date":"2025-03-20T16:15:46","date_gmt":"2025-03-20T15:15:46","guid":{"rendered":"https:\/\/mitur.gob.sv\/utravel\/sin-categoria\/pollo-campestre-usulutan-piloto\/"},"modified":"2025-03-20T16:15:46","modified_gmt":"2025-03-20T15:15:46","slug":"pollo-campestre-usulutan-piloto","status":"publish","type":"post","link":"https:\/\/elsalvador.travel\/esp\/en\/pollo-campestre-usulutan-piloto\/","title":{"rendered":"Pollo Campestre, Usulut\u00e1n Piloto"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[224,223],"tags":[289,30],"class_list":["post-13016","post","type-post","status-publish","format-standard","hentry","category-alimentacion-2","category-servicio","tag-alimentacionusulutan","tag-usulutan"],"acf":{"photo_gallery":{"galeria_de_imagenes":[[]]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 15:55:03","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/elsalvador.travel\/esp\/en\/wp-json\/wp\/v2\/posts\/13016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elsalvador.travel\/esp\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elsalvador.travel\/esp\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elsalvador.travel\/esp\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elsalvador.travel\/esp\/en\/wp-json\/wp\/v2\/comments?post=13016"}],"version-history":[{"count":0,"href":"https:\/\/elsalvador.travel\/esp\/en\/wp-json\/wp\/v2\/posts\/13016\/revisions"}],"wp:attachment":[{"href":"https:\/\/elsalvador.travel\/esp\/en\/wp-json\/wp\/v2\/media?parent=13016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elsalvador.travel\/esp\/en\/wp-json\/wp\/v2\/categories?post=13016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elsalvador.travel\/esp\/en\/wp-json\/wp\/v2\/tags?post=13016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}